{"id":3,"date":"2026-04-09T11:46:37","date_gmt":"2026-04-09T14:46:37","guid":{"rendered":"http:\/\/arterra.local\/?page_id=3"},"modified":"2026-05-06T11:01:52","modified_gmt":"2026-05-06T14:01:52","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/arterra.siteup.dev\/en\/politica-de-privacidade\/","title":{"rendered":"Pol\u00edtica de privacidade"},"content":{"rendered":"<div class=\"caixa-container-body overflow-hidden\">\n<p><b>POL\u00cdTICA DE PRIVACIDADE DA ARTERRA TURISMO<\/b><\/p>\n<p><b>Atualizada em 05\/08\/2021<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo se compromete em proteger a sua privacidade e garantir seus direitos.<\/p>\n<p>&nbsp;<\/p>\n<p>Por isso, na presente pol\u00edtica de privacidade, nos termos da Lei Geral de Prote\u00e7\u00e3o de Dados (Lei Federal n. 13.709\/2018), esclarecemos quais informa\u00e7\u00f5es s\u00e3o coletadas dos Clientes, a forma como esses dados s\u00e3o manipulados e os direitos dos propriet\u00e1rios dos dados.<\/p>\n<p>&nbsp;<\/p>\n<p>A Lei Geral de Prote\u00e7\u00e3o de Dados (LGPD) regula como as empresas podem tratar os dados pessoais e confere a voc\u00ea uma s\u00e9rie de direitos que podem ser exercidos a qualquer momento pelos titulares dos dados. Esses direitos garantem que voc\u00ea tenha transpar\u00eancia, acesso e controle em rela\u00e7\u00e3o \u00e0s pr\u00e1ticas de tratamento com os seus dados pessoais.<\/p>\n<p>&nbsp;<\/p>\n<p>Para a finalidade da presente pol\u00edtica de privacidade, ser\u00e3o considerados como Clientes:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Os \u201cUsu\u00e1rios da Loja Virtual\u201d da lojista;<\/li>\n<li>Os \u201cCompradores\u201d ou \u201cClientes finais\u201d, estes os usu\u00e1rios que preencheram formul\u00e1rio ou de qualquer forma inclu\u00edram dados pelas lojas virtuais e redes sociais da lojista).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>A pol\u00edtica \u00e9 aplic\u00e1vel a todos os clientes que acessarem ou converterem nas lojas virtuais, landing pages, redes sociais, etc, disponibilizados pela Arterra Turismo e suas empresas afiliadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Caso n\u00e3o concorde com os termos deste Instrumento, \u00e9 importante que interrompa qualquer tipo de uso de nossos softwares, sistemas, ferramentas e lojas virtuais; bem como n\u00e3o insira qualquer informa\u00e7\u00e3o de dados pessoais em nossas ferramentas autom\u00e1ticas de captura de informa\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>Em caso de d\u00favidas, entre em contato conosco pelo email arterra.turismo@gmail.com. Ser\u00e1 um prazer lhe orientar.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Controle e responsabilidade sobre os dados<\/b><\/h2>\n<p>A Lei Federal n. 13.709\/2018 (Lei Geral de Prote\u00e7\u00e3o de Dados) detalha dois principais agentes e suas responsabilidades em rela\u00e7\u00e3o aos dados:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Controlador: \u00e9 a empresa que controla os dados dos titulares. \u00c9 respons\u00e1vel pela coleta e utiliza\u00e7\u00e3o dos dados conforme permiss\u00e3o do titular e de acordo com as finalidades da lei. Considerado pela lei como respons\u00e1vel prim\u00e1rio pelos dados. De forma simples, \u00e9 quem \u00e9 respons\u00e1vel pelo que ser\u00e1 feito (\u201ctratamento\u201d) com os dados.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>Operador: \u00e9 a empresa que o controlador utiliza para realizar opera\u00e7\u00f5es de tratamento espec\u00edficas com os dados, tais como armazenar e processar os dados pessoais coletados. Considerado pela lei como respons\u00e1vel secund\u00e1rio pelos dados. De forma simples, ela executa o que o controlador decide sobre o que ser\u00e1 feito (\u201ctratamento\u201d) com os dados.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo \u00e9 considerada\u00a0<b>controladora<\/b>\u00a0de dados dos seus Clientes e respons\u00e1vel pelo tratamento e prote\u00e7\u00e3o de dados capturados por esta loja virtual, suas ferramentas, iscas ou outras formas neste meio digital. Portanto, o exerc\u00edcio dos seus direitos enquanto titular dever\u00e1 ser exercido perante esta, na forma descrita neste documento.<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Defini\u00e7\u00f5es de Cliente<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p>Para as finalidades desta pol\u00edtica de privacidade, o termo Cliente, quanto escrito em letra mai\u00fascula, dever\u00e1 contemplar:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Usu\u00e1rios da Loja Virtual: qualquer pessoa (f\u00edsica ou jur\u00eddica) que realize o contato ou interaja com nossos canais digitais e\/ou demonstram interesse em nossos produtos ou servi\u00e7os disponibilizados na loja virtual.<\/li>\n<li>Compradores: usu\u00e1rios da loja virtual que preencheram formul\u00e1rio e\/ou realizaram um pedido pela loja virtual.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Ao entrar em contato com a Arterra Turismo, a partir de funcionalidades dispon\u00edveis nas lojas virtuais, dados pessoais de identifica\u00e7\u00e3o ou de outra natureza com intuito de obter informa\u00e7\u00f5es sobre servi\u00e7os ou produtos ou de requerer a presta\u00e7\u00e3o de um servi\u00e7o, este usu\u00e1rio ser\u00e1 caracterizado como \u201cCompradores\u201d e, portanto, a presente pol\u00edtica de privacidade tamb\u00e9m se aplicar\u00e1 a voc\u00ea.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>1. Quais dados s\u00e3o coletados?<\/b><\/h2>\n<p>Os dados pessoais que podem ser coletados pela Arterra Turismo no \u00e2mbito desta Pol\u00edtica s\u00e3o:<\/p>\n<p>&nbsp;<\/p>\n<p><b>Usu\u00e1rios da Loja Virtual<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Dados de navega\u00e7\u00e3o: por exemplo, endere\u00e7o IP, localiza\u00e7\u00e3o \u2013 pa\u00eds, informa\u00e7\u00f5es sobre as p\u00e1ginas visitadas pelo usu\u00e1rio dentro da loja virtual, tempo de acesso na loja virtual, tempo de navega\u00e7\u00e3o em cada p\u00e1gina, an\u00e1lise de rastreamento de cliques).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Embora a Arterra Turismo n\u00e3o recolha estas informa\u00e7\u00f5es para as associar a Usu\u00e1rios espec\u00edficos, \u00e9 poss\u00edvel identificar esses Usu\u00e1rios diretamente atrav\u00e9s destas informa\u00e7\u00f5es ou pelo uso de outras informa\u00e7\u00f5es \u00e0s quais a Arterra Turismo tenha acesso.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Cookies: pequenos arquivos de texto que podem ser enviados e registrados no computador do Usu\u00e1rio que lembram as lojas virtuais visitadas, proporcionando uma melhor experi\u00eancia para o usu\u00e1rio na pr\u00f3xima vez que as lojas virtuais sejam visitadas. Veja mais sobre Cookies na se\u00e7\u00e3o \u201cComo os dados s\u00e3o coletados\/processados\u201d.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Para Compradores<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Informa\u00e7\u00f5es Cadastrais:<b>\u00a0<\/b>al\u00e9m das informa\u00e7\u00f5es elencadas para os \u201cusu\u00e1rios da loja virtual\u201d, ao realizar um contato para saber mais informa\u00e7\u00f5es ou adquirir os nossos servi\u00e7os, voc\u00ea poder\u00e1 nos fornecer: nome completo, n\u00famero do CPF, telefone de contato, endere\u00e7o de e-mail, informa\u00e7\u00f5es necess\u00e1rias para o passeio espec\u00edfico, informa\u00e7\u00f5es de pagamento, bem como outras informa\u00e7\u00f5es essenciais para a finaliza\u00e7\u00e3o da cota\u00e7\u00e3o ou compra, que ser\u00e3o exibidas ao seu titular.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Atente que, a depender dos servi\u00e7os, dados de menores ou sens\u00edveis poder\u00e3o ser requisitados. Em tais casos, garantimos o tratamento adequado, nos termos da Lei.<\/p>\n<p>&nbsp;<\/p>\n<p>Veja abaixo algumas das informa\u00e7\u00f5es cadastrais que poder\u00e3o ser coletadas:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table class=\"Table\" style=\"border-collapse: collapse; border: solid black 1.0pt;\" width=\"601\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"247\"><b>Dados coletados<\/b><\/td>\n<td valign=\"top\" width=\"171\"><b>Cliente<\/b><\/td>\n<td valign=\"top\" width=\"183\"><b>Como \u00e9 capturado<\/b><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"247\">Nome, e-mail, telefone, CPF, produto ou servi\u00e7o de interesse.<\/p>\n<p>&nbsp;<\/p>\n<p>{{Incluir todas as informa\u00e7\u00f5es pass\u00edveis de captura pelos usu\u00e1rios}}<\/td>\n<td valign=\"top\" width=\"171\">Compradores<\/td>\n<td valign=\"top\" width=\"183\">Formul\u00e1rios de compra na loja virtual<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"247\">Informa\u00e7\u00f5es de pagamento: N\u00famero do cart\u00e3o, titular, vencimento, c\u00f3digo de seguran\u00e7a, bandeira, n\u00famero de parcelas, endere\u00e7o para cobran\u00e7a.<\/td>\n<td valign=\"top\" width=\"171\">Compradores<\/td>\n<td valign=\"top\" width=\"183\">Formul\u00e1rios de compra na loja virtual<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"247\">Informa\u00e7\u00f5es t\u00e9cnicas, como endere\u00e7o de IP, dados de localiza\u00e7\u00e3o, informa\u00e7\u00f5es sobre cookies.<\/td>\n<td valign=\"top\" width=\"171\">Usu\u00e1rios da Loja Virtual<\/td>\n<td valign=\"top\" width=\"183\">Cookies, API de terceiros<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><b>Informa\u00e7\u00f5es de Navega\u00e7\u00e3o e Utiliza\u00e7\u00e3o da Loja Virtual:<\/b>\u00a0Al\u00e9m disso, podemos coletar outras informa\u00e7\u00f5es quando voc\u00ea navega na loja virtual, tais como funcionalidades acessadas e tempo de perman\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>2. Qual a finalidade do processamento de dados pessoais?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p>Os dados pessoais coletados podem ser tratados, sempre nos limites do permitido pela legisla\u00e7\u00e3o aplic\u00e1veis, para as seguintes finalidades:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Garantir a execu\u00e7\u00e3o do contrato de presta\u00e7\u00e3o de servi\u00e7os firmado com o Cliente Final;<\/li>\n<li>Permitir que a Arterra Turismo fa\u00e7a verifica\u00e7\u00f5es e pesquisas com o intuito de melhorar a qualidade dos produtos e servi\u00e7os prestados em harmonia com os interesses leg\u00edtimos da Arterra Turismo;<\/li>\n<li>Enviar comunica\u00e7\u00f5es comerciais e\/ou promocionais acerca de produtos e servi\u00e7os da Arterra Turismo, bem como fazer estudos de mercado (\u201cMarketing\u201d);<\/li>\n<li>Examinar sua solicita\u00e7\u00e3o e enviar a proposta comercial solicitada;<\/li>\n<li>Verificar sua identidade;<\/li>\n<li>Responder a eventuais pedidos de informa\u00e7\u00f5es adicionais<\/li>\n<li>Cumprir obriga\u00e7\u00f5es contratuais, legais ou regulat\u00f3rias em rela\u00e7\u00e3o a entidades terceiras p\u00fablicas ou privadas;<\/li>\n<li>Comunicar-se com o Cliente por telefone, email ou aplicativos de mensagens instant\u00e2neas quanto diretamente solicitado pelo usu\u00e1rio;<\/li>\n<li>Melhorar a experi\u00eancia do Usu\u00e1rio nos canais digitais (lojas virtuais) da Arterra Turismo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Atente que a utiliza\u00e7\u00e3o da nossa loja virtual somente dever\u00e1 ser efetivada se voc\u00ea consentir de forma direta, expressa e inequ\u00edvoca com as suas finalidades de utiliza\u00e7\u00e3o e com as nossas pol\u00edticas de privacidade e sigilo.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>3. Como os dados s\u00e3o coletados\/processados?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p>Para as finalidades descritas na se\u00e7\u00e3o acima, os dados pessoais ser\u00e3o processados exclusivamente de acordo com os termos descritos nesta Pol\u00edtica de Privacidade e de acordo com os princ\u00edpios de transpar\u00eancia, necessidade e legalidade, al\u00e9m dos demais previstos na Lei Geral de Prote\u00e7\u00e3o de Dados (Lei Federal 13.709\/2018).<\/p>\n<p>&nbsp;<\/p>\n<p>Os dados pessoais podem ser processados de forma impressa ou em formato eletr\u00f4nico autom\u00e1tico e atrav\u00e9s de correios, e-mail, telefone, fax e qualquer outro canal eletr\u00f4nico. S\u00e3o adotadas as medidas de seguran\u00e7a adequadas para evitar qualquer perda, uso injusto ou ilegal ou acesso n\u00e3o autorizado aos dados.<\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo se responsabiliza pela ado\u00e7\u00e3o e manuten\u00e7\u00e3o de medidas razo\u00e1veis de seguran\u00e7a, t\u00e9cnicas e administrativas para preven\u00e7\u00e3o de tratamento irregular ou il\u00edcito dos dados pessoais dos Clientes, inclusive hip\u00f3teses n\u00e3o autorizadas de acesso, destrui\u00e7\u00e3o, perda, altera\u00e7\u00e3o ou comunica\u00e7\u00e3o dos dados.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, a Arterra Turismo exige que seus operadores de dados\u00a0 atualizem e testem, conforme as boas pr\u00e1ticas, seus sistemas de seguran\u00e7a com a finalidade de proteger seus dados pessoais.<\/p>\n<p>&nbsp;<\/p>\n<p>No entanto, embora trabalhemos com boas pr\u00e1ticas de prote\u00e7\u00e3o e seguran\u00e7a, nenhum servi\u00e7o web possui 100% de garantia contra invas\u00f5es e n\u00e3o podemos nos responsabilizar caso isso ocorra.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>4. Com quem os dados podem ser compartilhados?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p><b>Para Usu\u00e1rios da Loja Virtual<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo n\u00e3o divulgar\u00e1 nenhum dado pessoal que identifique diretamente o Usu\u00e1rio, sem seu consentimento pr\u00e9vio, exceto nos casos em que a divulga\u00e7\u00e3o seja necess\u00e1ria para o cumprimento de obriga\u00e7\u00f5es legais e contratuais, por ordem de autoridades judicial ou administrativa, para exercer um direito legal ou com o intuito de atingir uma das finalidades indicadas nesta Pol\u00edtica de Privacidade.<\/p>\n<p>&nbsp;<\/p>\n<p>Os dados pessoais podem ser processados por terceiros que operem em nome e por conta da Arterra Turismo (\u201cOperadores\u201d), em virtude de obriga\u00e7\u00f5es contratuais espec\u00edficas e com o intuito de cumprir uma ou mais finalidades, conforme indicado na se\u00e7\u00e3o espec\u00edfica.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Para Compradores<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo poder\u00e1 compartilhar seus dados pessoais com terceiros ou parceiros de neg\u00f3cios, que sejam relevantes para fins de viabilizar a presta\u00e7\u00e3o dos servi\u00e7os contratadas. O referido compartilhamento ocorre com base nos seguintes crit\u00e9rios e para as finalidades descritas abaixo.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Prestadores de servi\u00e7os:<\/b>\u00a0essas empresas trabalham com a Arterra Turismo para viabilizar ou aprimorar o cumprimento das finalidades listadas no cap\u00edtulo anterior (\u201cPara quais finalidades coletamos seus dados?\u201d). S\u00e3o exemplos os servi\u00e7os de (i) desenvolvimento ou melhorias nos canais digitais, e (ii) cria\u00e7\u00e3o\/gest\u00e3o de a\u00e7\u00f5es de marketing para a Arterra Turismo relacionadas direta ou indiretamente aos canais digitais, produtos e servi\u00e7os da Arterra Turismo.<\/li>\n<\/ul>\n<p>Esses fornecedores recebem suas informa\u00e7\u00f5es com a finalidade espec\u00edfica de prestar servi\u00e7os \u00e0 Arterra Turismo e n\u00e3o possuem quaisquer direitos de uso de suas informa\u00e7\u00f5es fora dessa hip\u00f3tese.<\/p>\n<p>Algumas das aplica\u00e7\u00f5es prestadoras de servi\u00e7o que poder\u00e3o receber seus dados s\u00e3o: Paytour,\u00a0[listagem de empresas que poder\u00e3o receber, como operadoras, o acesso aos dados dos clientes].<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Institui\u00e7\u00f5es Financeiras:\u00a0<\/b>A Arterra Turismo compartilhar\u00e1 seus dados pessoais com as institui\u00e7\u00f5es financeiras parceiras para fins de processamento e pagamento das transa\u00e7\u00f5es efetuadas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Requisi\u00e7\u00e3o Judicial:<\/b>\u00a0A Arterra Turismo pode compartilhar dados pessoais em caso de requisi\u00e7\u00e3o judicial ou mediante determina\u00e7\u00e3o de autoridade competente, nos termos da lei.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Bancos de dados dos demais canais digitais da Arterra Turismo<\/b>: ao solicitar uma proposta comercial em uma loja virtual de uma das marcas da Arterra Turismo, seus dados integrar\u00e3o a base de dados dos canais digitais das demais marcas da empresa. Assim, voc\u00ea poder\u00e1 passar a receber comunica\u00e7\u00f5es de marketing dos produtos e servi\u00e7os identificados pelas demais marcas da Arterra Turismo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>A Paytour, empresa fornecedora da solu\u00e7\u00e3o Paytour para a lojista Arterra Turismo, \u00e9 mera operadora dos dados, fornecendo apenas a licen\u00e7a de uso da sua plataforma e-commerce para a Arterra Turismo.<\/p>\n<p>&nbsp;<\/p>\n<p>Entretanto a Paytour, operadora de dados da Arterra Turismo, poder\u00e1 utilizar instru\u00e7\u00f5es eletr\u00f4nicas, conhecidas como \u201ccookies\u201d que ser\u00e3o enviadas ao browser e armazenadas no disco do seu computador. A finalidade dos cookies \u00e9 verificar quem s\u00e3o os usu\u00e1rios da loja virtual da Arterra Turismo, para, eventualmente, facilitar sua navega\u00e7\u00e3o com as caracter\u00edsticas, prefer\u00eancias e qualidade das informa\u00e7\u00f5es veiculadas por seus cadastrados.<\/p>\n<p>&nbsp;<\/p>\n<p>Veja abaixo os tipos de cookies que poder\u00e3o ser utilizados:<\/p>\n<p>&nbsp;<\/p>\n<table class=\"Table\" style=\"border-collapse: collapse; border: solid black 1.0pt;\" width=\"600\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"191\"><b>Cookies de terceiros<\/b><\/td>\n<td valign=\"top\" width=\"409\">Podem ser inseridos pelo controlador dos dados para que ferramentas parceiras acessem as informa\u00e7\u00f5es. Ex.: Facebook Pixel, Youtube, Google Analytics, etc.<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"191\"><b>Cookies de sess\u00e3o<\/b><\/td>\n<td valign=\"top\" width=\"409\">Podem ser usados para persistir o login dos Usu\u00e1rios da Loja Virtual, rastreando sua atividade dentro da ferramenta Paytour<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"191\"><b>Cookies para registro de UTM<\/b><\/td>\n<td valign=\"top\" width=\"409\">Podem ser usados para envio dos dados de UTM nas convers\u00f5es dos canais.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>A maioria dos navegadores de internet permite algum tipo de controle de cookies por meio das configura\u00e7\u00f5es pessoais, em \u201cGerenciar cookies\u201d. Para saber mais sobre os cookies e como eles s\u00e3o armazenados, voc\u00ea pode visitar a p\u00e1gina Techtudo [<a href=\"https:\/\/www.techtudo.com.br\/noticias\/2018\/10\/o-que-sao-cookies-entenda-os-dados-que-os-sites-guardam-sobre-voce.ghtml\" target=\"_blank\" rel=\"noopener\">https:\/\/www.techtudo.com.br\/noticias\/2018\/10\/o-que-sao-cookies-entenda-os-dados-que-os-sites-guardam-sobre-voce.ghtm<\/a>l].<\/p>\n<p>&nbsp;<\/p>\n<h2><b>5. Quais os direitos do titular dos dados?<\/b><\/h2>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo garante o cumprimento \u00e0 Lei Federal n. 13.709\/2018 (Lei Geral de Prote\u00e7\u00e3o de Dados \u2013 LGPD), assegurando o cumprimento aos princ\u00edpios e fundamentos legais no tratamento de dados e a garantia dos direitos aos seus titulares.<\/p>\n<p>&nbsp;<\/p>\n<p>Os seguintes direitos do titular de dados pessoais poder\u00e3o ser exercidos a qualquer momento, em conformidade com a legisla\u00e7\u00e3o aplic\u00e1vel, pelos Clientes mediante solicita\u00e7\u00e3o:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Confirma\u00e7\u00e3o da exist\u00eancia de tratamento dos dados pessoais;<\/li>\n<li>Acesso aos dados pessoais;<\/li>\n<li>Corre\u00e7\u00e3o de dados pessoais incompletos, inexatos ou desatualizados;<\/li>\n<li>Anonimiza\u00e7\u00e3o, bloqueio ou elimina\u00e7\u00e3o de dados desnecess\u00e1rios, excessivos ou tratados em desconformidade com o disposto na LGPD;<\/li>\n<li>Portabilidade dos dados pessoais para outro fornecedor de um servi\u00e7o ou produto, sujeito \u00e0 regulamenta\u00e7\u00e3o da autoridade nacional;<\/li>\n<li>Apagamento ou anonimiza\u00e7\u00e3o dos dados pessoais tratados com base no seu consentimento, exceto quando a lei autorizar a manuten\u00e7\u00e3o destes dados por outro fundamento;<\/li>\n<li>Informa\u00e7\u00f5es sobre as entidades p\u00fablicas e privadas com as quais a Arterra Turismo tenha realizado o uso compartilhado dos seus dados pessoais;<\/li>\n<li>Informa\u00e7\u00f5es sobre a possibilidade de n\u00e3o dar consentimento ao tratamento dos seus dados pessoais e sobre as consequ\u00eancias de tal a\u00e7\u00e3o; e<\/li>\n<li>Revoga\u00e7\u00e3o do seu consentimento, quando o tratamento tenha sido feito com base no consentimento do titular.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Os dados pessoais ser\u00e3o tratados pelo per\u00edodo considerado necess\u00e1rio para cumprir a finalidade para o qual foram coletados e a fim de proteger os interesses da Arterra Turismo em rela\u00e7\u00e3o a potenciais responsabilidades relacionadas.<\/p>\n<p>&nbsp;<\/p>\n<p>O consentimento eventualmente fornecido por voc\u00ea para outras atividades n\u00e3o relacionadas com a presta\u00e7\u00e3o de um servi\u00e7o espec\u00edfico solicitado pode ser revogado a qualquer momento. Com a revoga\u00e7\u00e3o do consentimento, os dados n\u00e3o poder\u00e3o mais ser tratados para as referidas finalidades, embora possam ser ainda tratados para a prote\u00e7\u00e3o dos interesses da Arterra Turismo.<\/p>\n<h2><b>6. Como posso exercer meus direitos como titular dos dados?<\/b><\/h2>\n<p>Em caso de d\u00favidas, entre em contato com a empresa por meio do e-mail arterra.turismo@gmail.com.<\/p>\n<p>&nbsp;<\/p>\n<p>[Acrescentar dados do encarregado, caso haja].<\/p>\n<p>&nbsp;<\/p>\n<p>Para exercer os direitos apresentados na Se\u00e7\u00e3o \u201cQUAIS OS DIREITOS DO TITULAR DOS DADOS\u201d, \u00e9 necess\u00e1rio enviar um email para o endere\u00e7o arterra.turismo@gmail.com com o t\u00edtulo\u00a0<b>[LGPD] Nome do titular dos dados<\/b>, informando, no corpo do email, quais a\u00e7\u00f5es deseja realizar (confirmar exist\u00eancia de dados, acessar, migrar, editar, anonimizar, excluir, revogar consentimento). \u00c9 necess\u00e1rio tamb\u00e9m comprovar a titularidade dos dados, por meio da remessa de documento oficial com foto.<\/p>\n<p>&nbsp;<\/p>\n<p>A elimina\u00e7\u00e3o dos dados pessoais somente poder\u00e1 ser completa para dados pessoais que n\u00e3o sejam necess\u00e1rios para a Arterra Turismo cumprir com obriga\u00e7\u00f5es legais, contratuais, para prote\u00e7\u00e3o de seu leg\u00edtimo interesse e nas demais hip\u00f3teses admitidas legalmente.<\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo compartilha seus dados pessoais com terceiros para atingir determinadas finalidades, conforme estabelecido na Se\u00e7\u00e3o \u201cCOM QUEM OS DADOS S\u00c3O COMPARTILHADOS?\u201d desta Pol\u00edtica. Caso esses terceiros utilizem os seus dados pessoais para outras finalidades al\u00e9m das finalidades definidas na referida Se\u00e7\u00e3o e acordadas com a Arterra Turismo, eles se tornar\u00e3o controladores independentes em rela\u00e7\u00e3o aos tratamentos dos dados pessoais para as finalidades alheias \u00e0 Pol\u00edtica e ser\u00e3o exclusivamente respons\u00e1veis por tais tratamentos.<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Sobre atualiza\u00e7\u00f5es na pol\u00edtica de privacidade<\/b><\/h2>\n<p>A presente pol\u00edtica de privacidade poder\u00e1 ser atualizada periodicamente, sendo as altera\u00e7\u00f5es consideradas como de aplica\u00e7\u00e3o e vig\u00eancia imediata, exceto em caso de comunica\u00e7\u00e3o em contr\u00e1rio enviada pela Arterra Turismo.<\/p>\n<p>&nbsp;<\/p>\n<p>A Arterra Turismo tomar\u00e1 medidas razo\u00e1veis para comunicar os Clientes acerca das atualiza\u00e7\u00f5es nos termos desta pol\u00edtica. Tamb\u00e9m recomendamos visitar periodicamente esta p\u00e1gina para que voc\u00ea tenha conhecimento sobre as modifica\u00e7\u00f5es. Qualquer d\u00favida em rela\u00e7\u00e3o \u00e0 nossa pol\u00edtica de privacidade pode ser esclarecida entrando em contato conosco atrav\u00e9s do e-mail arterra.turismo@gmail.com<b>.<\/b><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>POL\u00cdTICA DE PRIVACIDADE DA ARTERRA TURISMO Atualizada em 05\/08\/2021 &nbsp; &nbsp; A Arterra Turismo se compromete em proteger a sua privacidade e garantir seus direitos. &nbsp; Por isso, na presente pol\u00edtica de privacidade, nos termos da Lei Geral de Prote\u00e7\u00e3o de Dados (Lei Federal n. 13.709\/2018), esclarecemos quais informa\u00e7\u00f5es s\u00e3o coletadas dos Clientes, a forma &#8230;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidade - ArTerra<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidade - ArTerra\" \/>\n<meta property=\"og:description\" content=\"POL\u00cdTICA DE PRIVACIDADE DA ARTERRA TURISMO Atualizada em 05\/08\/2021 &nbsp; &nbsp; A Arterra Turismo se compromete em proteger a sua privacidade e garantir seus direitos. &nbsp; Por isso, na presente pol\u00edtica de privacidade, nos termos da Lei Geral de Prote\u00e7\u00e3o de Dados (Lei Federal n. 13.709\/2018), esclarecemos quais informa\u00e7\u00f5es s\u00e3o coletadas dos Clientes, a forma ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arterra.siteup.dev\/en\/politica-de-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"ArTerra\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T14:01:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/politica-de-privacidade\\\/\",\"url\":\"https:\\\/\\\/arterra.siteup.dev\\\/politica-de-privacidade\\\/\",\"name\":\"Pol\u00edtica de privacidade - ArTerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#website\"},\"datePublished\":\"2026-04-09T14:46:37+00:00\",\"dateModified\":\"2026-05-06T14:01:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/politica-de-privacidade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arterra.siteup.dev\\\/politica-de-privacidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/politica-de-privacidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/arterra.siteup.dev\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#website\",\"url\":\"https:\\\/\\\/arterra.siteup.dev\\\/\",\"name\":\"ArTerra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arterra.siteup.dev\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#organization\",\"name\":\"ArTerra\",\"url\":\"https:\\\/\\\/arterra.siteup.dev\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arterra.siteup.dev\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/arterra.siteup.dev\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo.svg\",\"width\":199,\"height\":48,\"caption\":\"ArTerra\"},\"image\":{\"@id\":\"https:\\\/\\\/arterra.siteup.dev\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidade - ArTerra","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica de privacidade - ArTerra","og_description":"POL\u00cdTICA DE PRIVACIDADE DA ARTERRA TURISMO Atualizada em 05\/08\/2021 &nbsp; &nbsp; A Arterra Turismo se compromete em proteger a sua privacidade e garantir seus direitos. &nbsp; Por isso, na presente pol\u00edtica de privacidade, nos termos da Lei Geral de Prote\u00e7\u00e3o de Dados (Lei Federal n. 13.709\/2018), esclarecemos quais informa\u00e7\u00f5es s\u00e3o coletadas dos Clientes, a forma ...","og_url":"https:\/\/arterra.siteup.dev\/en\/politica-de-privacidade\/","og_site_name":"ArTerra","article_modified_time":"2026-05-06T14:01:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arterra.siteup.dev\/politica-de-privacidade\/","url":"https:\/\/arterra.siteup.dev\/politica-de-privacidade\/","name":"Pol\u00edtica de privacidade - ArTerra","isPartOf":{"@id":"https:\/\/arterra.siteup.dev\/#website"},"datePublished":"2026-04-09T14:46:37+00:00","dateModified":"2026-05-06T14:01:52+00:00","breadcrumb":{"@id":"https:\/\/arterra.siteup.dev\/politica-de-privacidade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arterra.siteup.dev\/politica-de-privacidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arterra.siteup.dev\/politica-de-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arterra.siteup.dev\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidade"}]},{"@type":"WebSite","@id":"https:\/\/arterra.siteup.dev\/#website","url":"https:\/\/arterra.siteup.dev\/","name":"ArTerra","description":"","publisher":{"@id":"https:\/\/arterra.siteup.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arterra.siteup.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/arterra.siteup.dev\/#organization","name":"ArTerra","url":"https:\/\/arterra.siteup.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arterra.siteup.dev\/#\/schema\/logo\/image\/","url":"https:\/\/arterra.siteup.dev\/wp-content\/uploads\/2026\/04\/logo.svg","contentUrl":"https:\/\/arterra.siteup.dev\/wp-content\/uploads\/2026\/04\/logo.svg","width":199,"height":48,"caption":"ArTerra"},"image":{"@id":"https:\/\/arterra.siteup.dev\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":1,"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":598,"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/598"}],"wp:attachment":[{"href":"https:\/\/arterra.siteup.dev\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}